{"id":27474,"date":"2022-06-18T04:52:06","date_gmt":"2022-06-18T04:52:06","guid":{"rendered":"https:\/\/emperorcruises.com\/charter-cruises-in-nha-trang\/"},"modified":"2026-04-13T05:12:19","modified_gmt":"2026-04-13T05:12:19","slug":"crociere-charter-a-nha-trang","status":"publish","type":"page","link":"https:\/\/emperorcruises.com\/it\/crociere-charter-a-nha-trang\/","title":{"rendered":"Crociere charter a Nha Trang"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27474\" class=\"elementor elementor-27474 elementor-21410\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a36902 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-stretched elementor-section-height-default sc_fly_static\" data-id=\"3a36902\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fb4331 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9fb4331\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3769f12 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3769f12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-container{--container-widget-width:100%}.e-container>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-container>.elementor-widget-spacer>.elementor-widget-container,.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d90b52e sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"d90b52e\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title color_style_link2 sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">EMPEROR CRUISES nha trang <\/span><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag trx_addons_inline_650615790\"\n\t\t\t><span class=\"sc_item_title_text\">Crociere charter a Nha Trang<\/span><\/h1><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1cca8 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"ad1cca8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3af5f09 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3af5f09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-06df3b2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"06df3b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38ba800 elementor-view-default sc_fly_static elementor-widget elementor-widget-icon\" data-id=\"38ba800\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#anchor\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14.626\" height=\"8.639\" viewBox=\"0 0 14.626 8.639\"><g id=\"down-arrow\" transform=\"translate(0 -70.698)\"><g id=\"Group_8820\" data-name=\"Group 8820\" transform=\"translate(0 100.698)\"><path id=\"Path_6507\" data-name=\"Path 6507\" d=\"M14.392,101.42l-.479-.482a.8.8,0,0,0-1.132,0L7.316,106.4l-5.472-5.472a.8.8,0,0,0-1.132,0l-.479.479a.8.8,0,0,0,0,1.131l6.515,6.538a.818.818,0,0,0,.567.257h0a.818.818,0,0,0,.566-.257l6.508-6.52a.808.808,0,0,0,.234-.571A.8.8,0,0,0,14.392,101.42Z\" transform=\"translate(0 -130.698)\"><\/path><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73bf6e9 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"73bf6e9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-076779a elementor-section-stretched scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"076779a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc58516 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"cc58516\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87c1a09 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"87c1a09\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7e4835 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"b7e4835\" data-element_type=\"section\" id=\"anchor\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-ee8667e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ee8667e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-caf3087 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"caf3087\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca0ee5d sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"ca0ee5d\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">Le prime crociere all-inclusive del Vietnam nella baia di Nha Trang<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Crociere charter a Nha Trang<\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e30ae97 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e30ae97\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e255a sc_height_small sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"12e255a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-352c34d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"352c34d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7400877 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7400877\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-680c7dc sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"680c7dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d8dfbd sc_fly_static elementor-widget elementor-widget-trx_widget_slider\" data-id=\"7d8dfbd\" data-element_type=\"widget\" data-widget_type=\"trx_widget_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"widget_area sc_widget_slider\"><aside class=\"widget widget_slider\">\t\t\t<div class=\"slider_wrap slider_engine_swiper\">\n\t\t\t\t<div class=\"slider_outer slider_swiper_outer slider_style_default slider_outer_direction_horizontal slider_outer_multi slider_outer_nopagination slider_outer_controls slider_outer_controls_side slider_outer_nocentered slider_outer_overflow_visible slider_outer_notitles\"><div class=\"slider_container slider_swiper swiper-slider-container slider_controls slider_controls_side slider_nocentered slider_overflow_visible slider_notitles slider_noresize slider_swipe slider_height_auto slider_direction_horizontal slider_nopagination slider_multi slider_type_images\" data-ratio=\"16:9\" data-interval=\"7000\" data-speed=\"600\" data-effect=\"swap\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-slides-per-view=\"2\" data-slides-space=\"60\" data-slides-centered=\"0\" data-slides-overflow=\"1\" data-mouse-wheel=\"0\" data-autoplay=\"1\" data-loop=\"1\" data-free-mode=\"0\" data-slides-min-width=\"220\"><div class=\"slider-wrapper swiper-wrapper\"><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/slide3-ec.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/slide3-ec.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/5-Relax-on-boat.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/5-Relax-on-boat.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/P1150358.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/P1150358.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/8-Transfe-by-speedboat.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/8-Transfe-by-speedboat.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/17204965580_8621e309a4_k3.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/17204965580_8621e309a4_k3.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Basket-Boat.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Basket-Boat.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Copy-of-Thuyen-trong-suot-2.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Copy-of-Thuyen-trong-suot-2.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/anh-nho-1.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/anh-nho-1.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Transparent-Kayaks-Nha-Trang-Vietnam-EmperorCruises.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Transparent-Kayaks-Nha-Trang-Vietnam-EmperorCruises.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Mieu-island-1.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Mieu-island-1.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/P1150568.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/P1150568.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/IMG_9878.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/IMG_9878.jpg\" alt=\"\"><\/div><\/div><div class=\"slider_controls_wrap\"><a class=\"slider_prev swiper-button-prev\" href=\"#\"><\/a><a class=\"slider_next swiper-button-next\" href=\"#\"><\/a><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t<\/aside><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa013e4 sc_layouts_hide_on_mobile sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"fa013e4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8e8ca0 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e8e8ca0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8e1b972 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8e1b972\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39555c4 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"39555c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h5 style=\"text-align: justify;\"><strong>RICORDI PER DURARE UNA VITA<\/strong><\/h5>\n<p style=\"text-align: justify;\">Offriamo charter privati \u200b\u200bper crociere di un giorno, cocktail e cene al tramonto e crociere per feste sia per charter privati \u200b\u200bche per charter professionali.<\/p>\n<p style=\"text-align: justify;\">Lo scopo di Emperor Cruises \u00e8 portare i tuoi clienti a vivere ogni momento con noi essendo trattati come re e regine, concedendosi servizi come musica, belle arti, architettura, cultura, cucine, storia e attivit\u00e0 all&#8217;aria aperta dove tutto \u00e8 tutto incluso.<\/p>\n<p style=\"text-align: justify;\">La nostra flotta include due itinerari giornalieri:\u00a0<a href=\"https:\/\/emperorcruises.com\/nha-trang-discovery-day-cruises\/\">Il Nha Trang Discovery Cruises<\/a>\u00a0e\u00a0<a href=\"https:\/\/emperorcruises.com\/sunset-cocktail-and-dinner-cruises\/\">Crociere con cocktail al tramonto e cena<\/a>. Garantiamo la partenza tutti i giorni, indipendentemente dal numero di passeggeri.<\/p>\n<p style=\"text-align: justify;\">Crociera sull&#8217;Emperor Junk \u00e8 un modo delizioso per vivere la baia di Nha Trang sia di giorno che di sera.<\/p>\n<p style=\"text-align: justify;\">Al tramonto, gli ospiti rimarranno meravigliati dai cieli colorati di rosso arancio e viola sorseggiando champagne ghiacciato, cocktail o birra ghiacciata accompagnati da deliziose tartine appetitose e un vietnamita cena a base di pesce.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Emperor Junk \u00e8 completamente autorizzato e assicurato per il trasporto di 32 passeggeri (fino a un massimo di 40 passeggeri) ed \u00e8 l&#8217;ideale per qualsiasi tipo di celebrazione, intrattenimento aziendale o promozione.<\/p>\n<p style=\"text-align: justify;\">Possiamo organizzare esperienze di crociera di interesse speciale come fotografie di matrimoni, compleanni, celebrazioni di anniversari, tour fotografici, pesca, snorkeling e immersioni subacquee.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2167489 sc_layouts_hide_on_mobile sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2167489\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd1c648 scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"bd1c648\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-653d793 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"653d793\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d01fe4c sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d01fe4c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-921dc40 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"921dc40\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-d7b7281 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"d7b7281\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b72df1 elementor-tabs-view-horizontal sc_tabs_icon_position_left sc_fly_static elementor-widget elementor-widget-tabs\" data-id=\"3b72df1\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{width:25%;-ms-flex-negative:0;flex-shrink:0}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active{border-right-style:none}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{height:999em;width:0;right:0;border-right-style:solid}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{top:0;-webkit-transform:translateY(-100%);-ms-transform:translateY(-100%);transform:translateY(-100%)}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after{top:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title{display:table-cell}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active{border-bottom-style:none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{bottom:0;height:0;width:999em;border-bottom-style:solid}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{right:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after{left:100%}.elementor-widget-tabs .elementor-tab-content,.elementor-widget-tabs .elementor-tab-title,.elementor-widget-tabs .elementor-tab-title:after,.elementor-widget-tabs .elementor-tab-title:before,.elementor-widget-tabs .elementor-tabs-content-wrapper{border:1px #d4d4d4}.elementor-widget-tabs .elementor-tabs{text-align:left}.elementor-widget-tabs .elementor-tabs-wrapper{overflow:hidden}.elementor-widget-tabs .elementor-tab-title{cursor:pointer;outline:var(--focus-outline,none)}.elementor-widget-tabs .elementor-tab-desktop-title{position:relative;padding:20px 25px;font-weight:700;line-height:1;border:solid transparent}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active{border-color:#d4d4d4}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:before{display:block;content:\"\";position:absolute}.elementor-widget-tabs .elementor-tab-desktop-title:focus-visible{border:1px solid #000}.elementor-widget-tabs .elementor-tab-mobile-title{padding:10px;cursor:pointer}.elementor-widget-tabs .elementor-tab-content{padding:20px;display:none}@media (max-width:767px){.elementor-tabs .elementor-tab-content,.elementor-tabs .elementor-tab-title{border-style:solid solid none}.elementor-tabs .elementor-tabs-wrapper{display:none}.elementor-tabs .elementor-tabs-content-wrapper{border-bottom-style:solid}.elementor-tabs .elementor-tab-content{padding:10px}}@media (min-width:768px){.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{-webkit-box-orient:vertical;-webkit-box-direction:normal;-ms-flex-direction:column;flex-direction:column}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-content-wrapper{-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-style:solid solid solid none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-content{border-style:none solid solid}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-stretch .elementor-tabs-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-horizontal .elementor-tab-title{width:100%}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-vertical .elementor-tab-title{height:100%}.elementor-tabs .elementor-tab-mobile-title{display:none}}<\/style>\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6231\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6231\" aria-expanded=\"false\">ITINERARIO DETTAGLIATO<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6232\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6232\" aria-expanded=\"false\">MAPPA DEL VIAGGIO<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6233\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6233\" aria-expanded=\"false\">PREZZO DEL TOUR<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6231\" aria-expanded=\"false\">ITINERARIO DETTAGLIATO<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6231\" tabindex=\"0\" hidden=\"false\"><h5 class=\"mkd-tour-item-plan-part-title\" style=\"text-align: center;\">Crociere charter<\/h5><div class=\"mkd-tour-item-plan-part-description\"><p style=\"text-align: justify;\"><strong>Charter per il tempo libero privati.<\/strong><\/p><p style=\"text-align: justify;\"><strong>Carte professionali<\/strong><\/p><p style=\"text-align: justify;\">Emperor Junk opera su base giornaliera programmata per singoli e piccoli gruppi. Inviaci un&#8217;e-mail a\u00a0<a href=\"mailto:salesteam@luxcruisesgroup.com\">salesteam@luxcruisesgroup.com<\/a>\u00a0per i dettagli.<\/p><p style=\"text-align: justify;\"><strong>Squadra di crociera con esperienza<\/strong><\/p><p style=\"text-align: justify;\">L&#8217;Emperor Cruises Captain ha molti anni di esperienza in crociera.<\/p><p style=\"text-align: justify;\">Per feste ed eventi impieghiamo personale professionale dei nostri punti vendita per fornire i massimi livelli di servizio.<strong>Carte private<\/strong><\/p><p style=\"text-align: justify;\">I charter privati \u200b\u200bsono accettati in base all&#8217;ordine di arrivo da parte di gruppi, individui o aziende.<\/p><p style=\"text-align: justify;\">\u00c8 disponibile una scelta di percorsi e pacchetti di ristorazione.<strong>Carta per professionisti<\/strong><\/p><p style=\"text-align: justify;\">Emperor Junk \u00e8 disponibile per charter professionali come produzione cinematografica, concorsi di bellezza o pubblicit\u00e0.<\/p><p style=\"text-align: justify;\"><strong>Disponibile:<\/strong><\/p><ul><li class=\"mkdf-icon-list-text\" style=\"text-align: justify;\">Cerimonia nuziale in crociera a tema Compleanno<\/li><li class=\"mkdf-icon-list-text\" style=\"text-align: justify;\">Anniversario di matrimonio<\/li><li class=\"mkdf-icon-list-text\" style=\"text-align: justify;\">Cena di gala festa in spiaggia per la luna di miele<\/li><li class=\"mkdf-icon-list-text\" style=\"text-align: justify;\">Riunioni di feste aziendali di ritiro dell&#8217;azienda<\/li><li class=\"mkdf-icon-list-text\" style=\"text-align: justify;\">Incentivi, conferenze, mostre Attivit\u00e0 di team building Musica dal vivo tradizionale o moderna Danza tradizionale o moderna Sfilata di moda<\/li><\/ul><\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6232\" aria-expanded=\"false\">MAPPA DEL VIAGGIO<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6232\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6232\" tabindex=\"0\" hidden=\"hidden\"><h5 style=\"text-align: center;\">DAY CRUISES<\/h5><p><img loading=\"lazy\" class=\"alignnone size-full wp-image-37553\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/06\/ECNT-map.jpg\" alt=\"\" width=\"1920\" height=\"1215\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/06\/ECNT-map.jpg 1920w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/06\/ECNT-map-840x532.jpg 840w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/06\/ECNT-map-410x259.jpg 410w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p><h5 class=\"wpb_heading wpb_singleimage_heading\" style=\"text-align: center;\">Sunset Cocktail and Dinner Cruise<\/h5><p><img loading=\"lazy\" class=\"aligncenter wp-image-21259 size-qwery-thumb-big\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Emperor-Cruises-Sunset-cocktail-dinner-cruises-800x473.jpg\" alt=\"\" width=\"800\" height=\"473\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6233\" aria-expanded=\"false\">PREZZO DEL TOUR<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6233\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6233\" tabindex=\"0\" hidden=\"hidden\"><strong>Prezzo su richiesta. Si prega di inviare richiesta a noi! Grazie.<\/strong><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a35069 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9a35069\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1e572 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0d1e572\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6117ddf sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"6117ddf\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_icon\" ><h4 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_icon sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">INVIA LA TUA RICHIESTA<\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77d9cde elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"77d9cde\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);-ms-flex-negative:0;flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:-webkit-box;display:-ms-flexbox;display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-container>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow,0)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-gg\"><use xlink:href=\"#fab-gg\" \/><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9235241 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"9235241\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b60b60 sc_fly_static elementor-widget elementor-widget-trx_sc_contact_form_7\" data-id=\"6b60b60\" data-element_type=\"widget\" data-widget_type=\"trx_sc_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f29024-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/27474#wpcf7-f29024-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"29024\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f29024-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/div>\n<div class=\"form-style-6\">\n\t<div class=\"columns_wrap\">\n\t<span class=\"wpcf7-form-control-wrap referlink\" data-name=\"referlink\"><input type=\"hidden\" name=\"referlink\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"><\/span>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-name\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-email\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-phone\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di telefono\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"column-1_1\">\n\t\t<p>Richiesta:\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-home\"><span class=\"wpcf7-form-control-wrap package\" data-name=\"package\"><input type=\"text\" name=\"package\" class=\"wpcf7-form-control wpcf7-text wpcf7dtx wpcf7dtx-text\" aria-invalid=\"false\" readonly=\"readonly\" value=\"Crociere charter a Nha Trang\"><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p>Data di arrivo\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"check-in\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"check-in\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap margin-bottom\">\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-textarea\"><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Per favore scrivi la tua richiesta!\" name=\"message\"><\/textarea><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<p><div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-2083235813\" class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAAB5BkqQC2N9TqUgz\" data-theme=\"light\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-refresh-expired=\"auto\" data-refresh-timeout=\"auto\" data-action=\"contact-form-7\" data-callback=\"turnstileCF7Callback\" data-appearance=\"always\"><\/div> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-2083235813\"> <style>#cf-turnstile-cf7-2083235813 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-2083235813')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-2083235813');},1000)}})})});<\/script> <\/div><br \/>\n<input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"Invia\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33e8639 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"33e8639\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff4bc8 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3ff4bc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d08846 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3d08846\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d0e003 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1d0e003\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a819c1 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1a819c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-112e782 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"112e782\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df314a6 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"df314a6\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">POTREBBE INTERESSARTI<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">TUTTE LE NOSTRE ESPERIENZE<\/span><\/h2><div class=\"sc_item_descr sc_title_descr sc_align_center\"><p>La nostra flotta include due esperienze di crociera uniche: la Nha Trang Discovery Cruises e la Sunset Cocktail and Dinner Cruises. Garantiamo la partenza tutti i giorni, indipendentemente dal numero di passeggeri.<\/p>\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352cead sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"352cead\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd43689 sc_fly_static elementor-widget elementor-widget-trx_sc_services\" data-id=\"bd43689\" data-element_type=\"widget\" data-widget_type=\"trx_sc_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sc_services sc_services_classic sc_services_featured_top\"><div class=\"sc_services_columns_wrap sc_item_columns sc_item_posts_container sc_item_columns_3 trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\"><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27437\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27437 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/08\/Emperor-Origin_Model_4-840x473.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/it\/crociere-di-un-giorno-alla-scoperta-di-nha-trang\/\">Crociere di un giorno alla scoperta di Nha Trang<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/it\/crociere-di-un-giorno-alla-scoperta-di-nha-trang\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/it\/crociere-di-un-giorno-alla-scoperta-di-nha-trang\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27452\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27452 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/DSC_0102-840x558.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/it\/crociera-al-tramonto-con-cocktail-e-cena\/\">Crociera al tramonto con cocktail e cena<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/it\/crociera-al-tramonto-con-cocktail-e-cena\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/it\/crociera-al-tramonto-con-cocktail-e-cena\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27465\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27465 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/slide3-ec-840x473.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/it\/combo-day-cruises-and-sunset-cocktail-dinner-cruises\/\">Crociere combinate di un giorno e crociere con cocktail e cena al tramonto<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/it\/combo-day-cruises-and-sunset-cocktail-dinner-cruises\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/it\/combo-day-cruises-and-sunset-cocktail-dinner-cruises\/\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0055001 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0055001\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90a3875 scheme_default elementor-section-stretched sc_layouts_hide_on_mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"90a3875\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20f1a6b sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"20f1a6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c769f0e sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c769f0e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff4ba2 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"fff4ba2\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">Cosa parlano di noi i nostri clienti<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">testimonianze<\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b87d26 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0b87d26\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c6c51b sc_fly_static elementor-widget elementor-widget-trx_sc_testimonials\" data-id=\"2c6c51b\" data-element_type=\"widget\" data-widget_type=\"trx_sc_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \t\tclass=\"sc_testimonials sc_testimonials_hover\"><div class=\"sc_testimonials_columns_wrap sc_item_columns trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\"><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27548\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Perfetto dall&#8217;inizio alla fine, scegli Royal Suite<\/strong>\u00a0&#8211; Bella nave con uno staff meraviglioso. Solo 8 camere rendono il viaggio davvero speciale. Abbiamo prenotato la suite reale, &#8220;King Room&#8221;. Questa stanza molto grande con spazio esterno davanti alla nave. Il letto dorme benissimo, la jacuzzi \u00e8 un&#8217;esperienza unica. Il nostro maggiordomo figlio era il migliore. Molto ben informato e cos\u00ec amichevole! Ha fatto di tutto per renderlo speciale. Abbiamo festeggiato il nostro anniversario una notte. Lo sforzo che la squadra ha dovuto affrontare \u00e8 stato brillante. Bouquet di rose fresche, una grande torta e un bel discorso del manager Quang. Ann, Abby e il barista Jack erano fantastici e attenti, cos\u00ec come la nostra guida turistica Wind. Se stai festeggiando un anniversario o vuoi proporti, fallo qui. Mi \u00e8 piaciuto anche l&#8217;itinerario delle 2 notti, 3 giorni in quanto ti offre una vista unica sulla baia su una barca pi\u00f9 piccola.<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"Jorrit88\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Jorrit88<\/h4>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27552\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Eccellenza e serenit\u00e0<\/strong> &#8211; Mio marito ed io ci siamo goduti una crociera di 2 notti con Emperor Cruises nella baia di Halong. Il personale era assolutamente delizioso e attento ad ogni tua esigenza. La cena \u00e8 stata abbondante e molto buona. Durante le nostre escursioni a terra, la nostra guida era ben informata, disponibile e preparata per tutto il pranzo, il tempo e tutto ci\u00f2 che era necessario per la sicurezza e il comfort. Abbiamo adorato l&#8217;intera esperienza e lo consigliamo vivamente quando visitiamo la zona. Un consiglio: l&#8217;opzione per 2 notti offriva la migliore opportunit\u00e0 per godersi davvero la zona.<br \/>\nTutte le 10 cabine sono dotate di bagno privato con balcone privato, vista panoramica sull&#8217;oceano e servizio di maggiordomo personale. La flotta Emperor Cruises \u00e8 progettata per essere un santuario che assicura che ogni momento sia importante per gli ospiti nella baia di Ha Long, una tappa obbligata nell&#8217;itinerario di viaggio di tutti i visitatori del Vietnam.<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"franee0409\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">franee0409<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">New York City, New York<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27556\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Scenario affascinante in una magnifica nave da crociera nella baia di Halong Bay!<\/strong> &#8211; La crociera con Emperor Cruise ad Halong rende la nostra vacanza pi\u00f9 speciale e memorabile in questo meraviglioso paese! Siamo stati su diverse navi da crociera internazionali, ma questa \u00e8 unica e autentica poich\u00e9 il concetto di questa barca presentava la storia e la cultura del Vietnam con dipinti molto dettagliati in ogni angolo a bordo. A parte la sua splendida barca, il team su questa barca \u00e8 eccellente, specialmente Chris che parla correntemente l&#8217;inglese tra tutti loro. La barca dell&#8217;imperatore offriva anche una variet\u00e0 di attivit\u00e0 all&#8217;interno e all&#8217;esterno delle escursioni, ma ovviamente puoi scegliere tra unirti o rimanere sulla nave principale per rilassarti. Il cibo \u00e8 perfetto e la quantit\u00e0 \u00e8 troppa! Questa nave \u00e8 davvero un 5* per noi! Basta aggiungere pi\u00f9 personale che parla inglese per una migliore comunicazione a bordo!<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"Rasmus Engkeb\u00f8lle\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Rasmus Engkeb\u00f8lle<\/h4>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><!-- \/.sc_testimonials -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfa3173 sc_layouts_hide_on_tablet sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"bfa3173\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f565c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7f565c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee1053a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ee1053a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c94be8 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"9c94be8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EMPEROR CRUISES nha trang Crociere charter a Nha Trang Le prime crociere all-inclusive del Vietnam nella baia di Nha Trang Crociere charter a Nha Trang Sperimenta ogni&nbsp;momento! RICORDI PER DURARE&hellip;<\/p>\n","protected":false},"author":1,"featured_media":23096,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/pages\/27474"}],"collection":[{"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/comments?post=27474"}],"version-history":[{"count":13,"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/pages\/27474\/revisions"}],"predecessor-version":[{"id":40956,"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/pages\/27474\/revisions\/40956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/media\/23096"}],"wp:attachment":[{"href":"https:\/\/emperorcruises.com\/it\/wp-json\/wp\/v2\/media?parent=27474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}