{"id":27400,"date":"2022-06-09T15:41:32","date_gmt":"2022-06-09T15:41:32","guid":{"rendered":"https:\/\/emperorcruises.com\/experience-hanoi-halong-bay-in-5-days\/"},"modified":"2026-04-13T05:11:23","modified_gmt":"2026-04-13T05:11:23","slug":"erleben-sie-hanoi-halong-bucht-in-5-tagen","status":"publish","type":"page","link":"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-5-tagen\/","title":{"rendered":"Erleben Sie Hanoi &#038; Halong Bucht in 5 Tagen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27400\" class=\"elementor elementor-27400\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a36902 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-stretched elementor-section-height-default sc_fly_static\" data-id=\"3a36902\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fb4331 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9fb4331\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3769f12 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3769f12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-container{--container-widget-width:100%}.e-container>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-container>.elementor-widget-spacer>.elementor-widget-container,.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d90b52e sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"d90b52e\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title color_style_link2 sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">EMPEROR CRUISES LEGACY HALONG<\/span><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag trx_addons_inline_287360072\"\n\t\t\t><span class=\"sc_item_title_text\">Erleben Sie Hanoi & Halong Bucht in 5 Tagen<\/span><\/h1><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1cca8 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"ad1cca8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3af5f09 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3af5f09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-06df3b2 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"06df3b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38ba800 elementor-view-default sc_fly_static elementor-widget elementor-widget-icon\" data-id=\"38ba800\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#anchor\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14.626\" height=\"8.639\" viewBox=\"0 0 14.626 8.639\"><g id=\"down-arrow\" transform=\"translate(0 -70.698)\"><g id=\"Group_8820\" data-name=\"Group 8820\" transform=\"translate(0 100.698)\"><path id=\"Path_6507\" data-name=\"Path 6507\" d=\"M14.392,101.42l-.479-.482a.8.8,0,0,0-1.132,0L7.316,106.4l-5.472-5.472a.8.8,0,0,0-1.132,0l-.479.479a.8.8,0,0,0,0,1.131l6.515,6.538a.818.818,0,0,0,.567.257h0a.818.818,0,0,0,.566-.257l6.508-6.52a.808.808,0,0,0,.234-.571A.8.8,0,0,0,14.392,101.42Z\" transform=\"translate(0 -130.698)\"><\/path><\/g><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73bf6e9 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"73bf6e9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-076779a elementor-section-stretched scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"076779a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc58516 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"cc58516\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87c1a09 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"87c1a09\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7e4835 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"b7e4835\" data-element_type=\"section\" id=\"anchor\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-ee8667e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ee8667e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-caf3087 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"caf3087\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca0ee5d sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"ca0ee5d\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">Vietnams allererste All-Inclusive-\u00dcbernachtkreuzfahrten in der Halong-Bucht<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Erleben Sie Hanoi & Halong Bucht in 5 Tagen<\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e30ae97 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e30ae97\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e255a sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"12e255a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-352c34d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"352c34d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7400877 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7400877\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-680c7dc sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"680c7dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d8dfbd sc_fly_static elementor-widget elementor-widget-trx_widget_slider\" data-id=\"7d8dfbd\" data-element_type=\"widget\" data-widget_type=\"trx_widget_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"widget_area sc_widget_slider\"><aside class=\"widget widget_slider\">\t\t\t<div class=\"slider_wrap slider_engine_swiper\">\n\t\t\t\t<div class=\"slider_outer slider_swiper_outer slider_style_default slider_outer_direction_horizontal slider_outer_multi slider_outer_nopagination slider_outer_controls slider_outer_controls_side slider_outer_nocentered slider_outer_overflow_visible slider_outer_notitles\"><div class=\"slider_container slider_swiper swiper-slider-container slider_controls slider_controls_side slider_nocentered slider_overflow_visible slider_notitles slider_noresize slider_swipe slider_height_auto slider_direction_horizontal slider_nopagination slider_multi slider_type_images\" data-ratio=\"16:9\" data-interval=\"7000\" data-speed=\"600\" data-effect=\"swap\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-slides-per-view=\"2\" data-slides-space=\"60\" data-slides-centered=\"0\" data-slides-overflow=\"1\" data-mouse-wheel=\"0\" data-autoplay=\"1\" data-loop=\"1\" data-free-mode=\"0\" data-slides-min-width=\"220\"><div class=\"slider-wrapper swiper-wrapper\"><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Restaurant-Lifestyle-11.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Restaurant-Lifestyle-11.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Restaurant-Lifestyle-13.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Restaurant-Lifestyle-13.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/Restaurant-Lifestyle-9.jpg.webp\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/Restaurant-Lifestyle-9.jpg.webp\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/King-Suite-8.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/King-Suite-8.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/Welcome-lifestyle-2.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/Welcome-lifestyle-2.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-17.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-17.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-1.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-1.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/King-Suite-3.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/King-Suite-3.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/intercon2.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/intercon2.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Room-Lifestle-1-1.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Room-Lifestle-1-1.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/metropole-hotel-4.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/metropole-hotel-4.jpg\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Sundeck-Lifestyle-2.jpg\" style=\"\"><img src=\"\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Sundeck-Lifestyle-2.jpg\" alt=\"\"><\/div><\/div><div class=\"slider_controls_wrap\"><a class=\"slider_prev swiper-button-prev\" href=\"#\"><\/a><a class=\"slider_next swiper-button-next\" href=\"#\"><\/a><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t<\/aside><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa013e4 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"fa013e4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8e8ca0 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e8e8ca0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8e1b972 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8e1b972\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39555c4 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"39555c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: justify;\"><strong>Erleben Sie Hanoi &amp; Halong-Bucht in 5 Tagen \u2013\u00a0<\/strong> Dieses f\u00fcnft\u00e4gige Erlebnis in Hanoi und der Halong-Bucht richtet sich an Reisende, die das Stadtleben von Hanoi auf eigene Faust erkunden, lokale Speisen in der Altstadt probieren und edle bestickte Seidenkleidung kaufen m\u00f6chten Bettw\u00e4sche, Bambus und mehr.<\/p>\n\n<h5 style=\"text-align: justify;\"><strong>\u00dcBER EMPEROR CRUISE HALONG<\/strong><\/h5>\n<p style=\"text-align: justify;\">Als erster Anbieter von Luxuskreuzfahrten, der Erlebnisreisen in der Halong-Bucht anbietet, ist die Flotte von Emperor Cruises als Zufluchtsort konzipiert, um sicherzustellen, dass jeder Moment f\u00fcr die G\u00e4ste z\u00e4hlt.\nDer Vorteil einer Luxuskreuzfahrt mit Emperor Cruises besteht darin, dass es sich, abgesehen davon, dass es sich um kleine Schiffe mit pers\u00f6nlichem Service und herausragenden Einrichtungen handelt, auf einer All-Inclusive-Basis h\u00e4ufig keine Rechnung am Ende zu bezahlen gibt, egal ob bei einer zwei- oder dreit\u00e4gigen Kreuzfahrt oder sogar eine Tageskreuzfahrt.<strong>\n<\/strong><\/p>\n\n<h5 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter wp-image-18452 size-qwery-thumb-masonry-big\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/ec-slide1-840x472.jpg\" alt=\"\" width=\"840\" height=\"472\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/ec-slide1-840x472.jpg 840w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/ec-slide1-1290x725.jpg 1290w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/ec-slide1-410x230.jpg 410w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/05\/ec-slide1.jpg 1400w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/h5>\n<h5 style=\"text-align: justify;\"><strong>\u00dcBER SOFITEL LEGEND METROPOLE HANOI<\/strong><\/h5>\n<p style=\"text-align: justify;\">Nur wenige Schritte vom Opernhaus im franz\u00f6sischen Viertel von Hano\u00ef entfernt bringt dieses legend\u00e4re Anwesen G\u00e4ste in engen Kontakt mit der Opulenz einer anderen \u00c4ra. Umgeben Sie sich mit Erbe, w\u00e4hrend Sie durch stattliche Korridore schlendern und eine dramatische Vergangenheit erkunden. Hinter der klassischen wei\u00dfen Fassade verbergen sich gr\u00fcne Fensterl\u00e4den, originale schmiedeeiserne Details und stattliche Holzvert\u00e4felungen aus \u00fcber einem Jahrhundert voller Geschichten. Stellen Sie sich auf die Gehwege, die den \u00fcppigen Rasen im Innenhof zieren, und tauchen Sie ein in die reichen Traditionen des Hotels.<\/p>\n\n<h5 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter wp-image-20865 size-qwery-thumb-big\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/8023ab9e6978bf705af960bf2f3a77c7-840x473.jpg\" alt=\"\" width=\"840\" height=\"473\" \/>\n273 \/ 5,000\nTranslation results\n<strong>AUSGANGSPUNKTE &amp; ANKUNFT:<\/strong><\/h5>\n<p style=\"text-align: justify;\">\u2022 <strong>Flughafen Noi Bai<\/strong>: Terminal 2, Internationaler Flughafen Noi Bai, Hanoi, Vietnam\n\u2022 <strong>Hanoi<\/strong>: Sofitel Legend Metropole Hanoi, 15 Ngo Quyen, Hanoi, Vietnam<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2167489 sc_layouts_hide_on_mobile sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2167489\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd1c648 scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"bd1c648\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-653d793 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"653d793\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d01fe4c sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d01fe4c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-042b731 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"042b731\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-94ee397 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"94ee397\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e73f8 elementor-tabs-view-horizontal sc_tabs_icon_position_left sc_fly_static elementor-widget elementor-widget-tabs\" data-id=\"11e73f8\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{width:25%;-ms-flex-negative:0;flex-shrink:0}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active{border-right-style:none}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{height:999em;width:0;right:0;border-right-style:solid}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{top:0;-webkit-transform:translateY(-100%);-ms-transform:translateY(-100%);transform:translateY(-100%)}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after{top:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title{display:table-cell}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active{border-bottom-style:none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{bottom:0;height:0;width:999em;border-bottom-style:solid}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{right:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after{left:100%}.elementor-widget-tabs .elementor-tab-content,.elementor-widget-tabs .elementor-tab-title,.elementor-widget-tabs .elementor-tab-title:after,.elementor-widget-tabs .elementor-tab-title:before,.elementor-widget-tabs .elementor-tabs-content-wrapper{border:1px #d4d4d4}.elementor-widget-tabs .elementor-tabs{text-align:left}.elementor-widget-tabs .elementor-tabs-wrapper{overflow:hidden}.elementor-widget-tabs .elementor-tab-title{cursor:pointer;outline:var(--focus-outline,none)}.elementor-widget-tabs .elementor-tab-desktop-title{position:relative;padding:20px 25px;font-weight:700;line-height:1;border:solid transparent}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active{border-color:#d4d4d4}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:before{display:block;content:\"\";position:absolute}.elementor-widget-tabs .elementor-tab-desktop-title:focus-visible{border:1px solid #000}.elementor-widget-tabs .elementor-tab-mobile-title{padding:10px;cursor:pointer}.elementor-widget-tabs .elementor-tab-content{padding:20px;display:none}@media (max-width:767px){.elementor-tabs .elementor-tab-content,.elementor-tabs .elementor-tab-title{border-style:solid solid none}.elementor-tabs .elementor-tabs-wrapper{display:none}.elementor-tabs .elementor-tabs-content-wrapper{border-bottom-style:solid}.elementor-tabs .elementor-tab-content{padding:10px}}@media (min-width:768px){.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{-webkit-box-orient:vertical;-webkit-box-direction:normal;-ms-flex-direction:column;flex-direction:column}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-content-wrapper{-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-style:solid solid solid none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-content{border-style:none solid solid}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-stretch .elementor-tabs-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-horizontal .elementor-tab-title{width:100%}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-vertical .elementor-tab-title{height:100%}.elementor-tabs .elementor-tab-mobile-title{display:none}}<\/style>\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1871\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">DETAILLIERT REISEROUTE<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1872\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1872\" aria-expanded=\"false\">EINSCHL\u00dcSSE<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1873\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1873\" aria-expanded=\"false\">REISEKARTE<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1874\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1874\" aria-expanded=\"false\">TOURPREIS<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">DETAILLIERT REISEROUTE<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1871\" tabindex=\"0\" hidden=\"false\"><h5 style=\"text-align: justify;\"><strong>TAG 1: ANKUNFT IN HANOI<\/strong><\/h5>\n<p style=\"text-align: justify;\">12.00 Uhr: Sie werden mit einem privaten Auto am Noi Bai International Airport zum Sofitel Legend Metropole Hanoi abgeholt.<\/p>\n<p style=\"text-align: justify;\">14.00 Uhr: Check-in im Sofitel Legend Metropole Hanoi. Sie erhalten Ihre GRAND PRESTIGE SUITE (mit Club Metropole Vorteilen) (Contemporary Opera Wing)<\/p>\n\n<h5 style=\"text-align: justify;\"><strong>TAG 2: HANOI \u2013 INTERNATIONALER KREUZFAHRTHAFEN HALONG -&gt; BAI TU LONG BUCHT -&gt; THIEN CANH SON H\u00d6HLE -&gt; CONG DO (SCHLAFBEREICH).<\/strong><\/h5>\n<p style=\"text-align: justify;\">8.00 Uhr: Abfahrt vom Sofitel Legend Metropole Hanoi zur Halong-Bucht mit einem bequemen Shuttlebus (optional)<\/p>\n<p style=\"text-align: justify;\">12:00: Bei der Ankunft bei Emperor Cruises am Halong International Cruise Port hei\u00dft Sie unser Team in unserer Lounge willkommen, bevor Sie an Bord gehen<\/p>\n<p style=\"text-align: justify;\">12:30: Unser Experiences Manager hilft Ihnen beim Einsteigen, um die Kreuzfahrt in der Bucht von Bai Tu Long zu beginnen<\/p>\n<p style=\"text-align: justify;\">13.00 Uhr: In unserem Restaurant Can Chanh auf dem Hauptdeck wird ein Mittagsmen\u00fc serviert. Genie\u00dfen Sie k\u00f6stliches vietnamesisches Essen, w\u00e4hrend Sie die Anmut der Bucht bewundern.<\/p>\n<p style=\"text-align: justify;\">15.30: Erkunden Sie das Gebiet der Insel Hon Co und der Co-H\u00f6hle (Grash\u00f6hle, auch bekannt als Thien Canh Son). Sie k\u00f6nnen die atemberaubende Aussicht auf die Bucht von Bai Tu Long von oben sowie den herrlichen langen wei\u00dfen Sandstrand der Insel Hon Co genie\u00dfen. Entspannen Sie anschlie\u00dfend am Strand, schwimmen Sie im kristallklaren Wasser und erkunden Sie die H\u00f6hle.<\/p>\n<p style=\"text-align: justify;\">16.30: R\u00fcckkehr zur Kreuzfahrt mit einem kleinen Boot 16.30: Weiterfahrt zum schwimmenden Dorf Vung Vieng, um Bambusboote zu besteigen, damit die Einheimischen Sie durch ihr Dorf und ihre Austernzuchtfelder rudern k\u00f6nnen. Kehren Sie mit dem Schnellboot zum Boot zur\u00fcck.<\/p>\n<p style=\"text-align: justify;\">17.20 Uhr: W\u00e4hlen Sie zwischen Kajakfahren, Massagen, einfach nur Entspannen oder Nachmittagstee und beobachten Sie, wie sich die Farbe des Himmels \u00e4ndert, wenn die Sonne untergeht.<\/p>\n<p style=\"text-align: justify;\">18.15: Nehmen Sie an der Kochvorf\u00fchrung unseres K\u00fcchenchefs teil und erproben Sie Ihre F\u00e4higkeiten in der Kunst der traditionellen vietnamesischen K\u00fcche (Zubereitung von Fr\u00fchlingsrollen) in einer wirklich atemberaubenden Umgebung.<\/p>\n<p style=\"text-align: justify;\">19.00 Uhr: Genie\u00dfen Sie unser \u00c0-la-carte-Gangmen\u00fc zum Abendessen an Bord, w\u00e4hrend Sie nachts den Charme der Bucht von Bai Tu Long erleben.<\/p>\n<p style=\"text-align: justify;\">21.00: Abendaktivit\u00e4ten: Genie\u00dfen Sie unseren Filmabend, Brettspiele oder unsere Massage- und Spa-Services oder gehen Sie sogar Tintenfisch angeln. \u00dcbernachtung an Bord von Emperor Cruises.<\/p>\n\n<h5 style=\"text-align: justify;\"><strong>TAG 3:<\/strong><\/h5>\n<p style=\"text-align: justify;\">06.00 \u2013 06.30: Begr\u00fc\u00dfen Sie einen neuen Tag mit einem atemberaubenden Sonnenaufgang in der Bucht von Bai Tu Long mit einer Vovinam-Session auf dem Sonnendeck.<\/p>\n<p style=\"text-align: justify;\">07.00 \u2013 07.45: Fangen Sie den morgendlichen Blick auf das Meer ein, w\u00e4hrend Sie das Fr\u00fchst\u00fcck im Restaurant genie\u00dfen.<\/p>\n<p style=\"text-align: justify;\">08.00 \u2013 08.15: Transfer zum kleinen Day Boat und Beginn der Kreuzfahrt, um die weiteste Sch\u00f6nheit der Bucht von Bai Tu Long zu bewundern.<\/p>\n<p style=\"text-align: justify;\">08.30 \u2013 10.00: Fahren Sie mit dem Kajak und entdecken Sie die Thay-H\u00f6hle \u2013 eine der gr\u00f6\u00dften &amp; gut versteckte H\u00f6hlen in der Bucht von Bai Tu Long.<\/p>\n<p style=\"text-align: justify;\">11.00 12.00 Besuch des Cong Dam-Gebiets \u2013 Naturpark Hon Xep \u2013 Tief in der Bai Tu Long Bay, den ber\u00fchmten versteckten Lagunen, die von majest\u00e4tischen Kalksteininseln und Inselchen mit wilden Str\u00e4nden bedeckt sind.<\/p >\n<p style=\"text-align: justify;\">12.30 \u2013 15.00: Genie\u00dfen Sie das Mittagessen im Restaurant auf einem Tagesboot<\/p>\n<p style=\"text-align: justify;\">16.00 \u2013 16.30: Transfer vom Tagesboot zur\u00fcck zum Hauptboot \u2013 Emperor Cruises Boot<\/p>\n<p style=\"text-align: justify;\">18.15 Uhr Genie\u00dfen Sie einen Massageservice oder entspannen Sie sich einfach oder versuchen Sie Ihre F\u00e4higkeiten in der Kunst der traditionellen vietnamesischen K\u00fcche (Zubereitung von Fr\u00fchlingsrollen) in einer wirklich atemberaubenden Umgebung.<\/p>\n<p style=\"text-align: justify;\">19.00: Genie\u00dfen Sie Ihr BBQ-Dinner an Bord, w\u00e4hrend Sie nachts den Charme der Bucht von Bai Tu Long erleben.<\/p>\n<p style=\"text-align: justify;\">21.00: Abendaktivit\u00e4ten: Genie\u00dfen Sie unseren Filmabend, Brettspiele oder unsere Massage- und Spa-Services oder gehen Sie sogar Tintenfisch angeln. \u00dcbernachtung an Bord von Emperor Cruises<\/p>\n\n<h5 style=\"text-align: justify;\"><strong>TAG 4: CONG DO (SCHLAFBEREICH) \u2013 THIEN CANH SON H\u00d6HLE \u2013 HALONG INTERNATIONALER KREUZFAHRTHAFEN<\/strong><\/h5>\n<p style=\"text-align: justify;\">6.30 \u2013 6.30 Uhr: Wachen Sie mit dem sanften Pl\u00e4tschern des Wassers gegen das Boot auf und die ersten Sonnenstrahlen k\u00fcndigen einen neuen Tag an. Bevor Sie das Fr\u00fchst\u00fcck genie\u00dfen, essen Sie Kekse und Tee und probieren Sie dann die Vovinam-Session auf dem Sonnendeck, w\u00e4hrend die Sonne \u00fcber der Bucht von Bai Tu Long aufgeht<\/p>\n<p style=\"text-align: justify;\">7.45 \u2013 8.45: Besuchen Sie das Fischerdorf Vung Vieng, das ber\u00fchmte Perlenz\u00fcchterdorf, um die Fischbecken der Einheimischen zu sehen. Fahren Sie weiter zum schwimmenden Dorf Vung Vieng, um Bambusboote zu besteigen, damit die Einheimischen Sie durch ihr Dorf und ihre Austernzuchtfelder rudern k\u00f6nnen. Kehren Sie mit dem Schnellboot\/Tender<\/p> zum Mutterboot zur\u00fcck\n<p style=\"text-align: justify;\">8.45: R\u00fcckkehr zur Kreuzfahrt mit einem kleinen Boot<\/p>\n<p style=\"text-align: justify;\">9.15: Gep\u00e4ck arrangieren und auschecken.<\/p>\n<p style=\"text-align: justify;\">11.15: Kommen Sie zur\u00fcck am Kai von Emperor Cruises in Halong City zur Ausschiffung, wo Ihr Fahrer darauf wartet, Sie zur\u00fcck zum Sofitel Legend Metropole Hanoi zu bringen<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1872\" aria-expanded=\"false\">EINSCHL\u00dcSSE<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1872\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1872\" tabindex=\"0\" hidden=\"hidden\"><h5 style=\"text-align: justify;\"><strong>EINSCHLUSS:\n<\/strong><\/h5>\n<div class=\"su-row\">\n<div class=\"su-column su-column-size-3-5\">\n<h6 class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\"><strong>LUXUS-EMPEROR-HALONG-KREUZFAHRT<\/strong><\/h6>\n<ul style=\"text-align: justify;\">\n <li>Kostenloser Transfer mit dem Privatwagen vom internationalen Flughafen Noi Bai zum Sofitel Legend Metropole Hotel<\/li>\n <li>Kostenloser Hin- und R\u00fccktransfer per Limousine Dcar zwischen Hanoi und Halong Bay<\/li>\n <li>Volle 3 Tage 2 N\u00e4chte Reiseroute auf der 5-Sterne Emperor Cruise Halong<\/li>\n <li>Erlesene Mahlzeiten an Bord der 3D2N-Kreuzfahrt: 02 Mittagsmen\u00fc, 02 Abendessen \u00e0 la carte, 02 Fr\u00fchst\u00fcck und 2 Brunch<\/li>\n <li>Englisch sprechender Butlerservice rund um die Uhr<\/li>\n <li>Livemusik, Kino, Bars &amp; Kunstgalerie<\/li>\n <li>Unbegrenzte Getr\u00e4nke: Wasser, Tee und Kaffee, Hauswein, Spirituosen, lokales Bier, Fruchts\u00e4fte, Erfrischungsgetr\u00e4nke, Cocktails, Mocktail.<\/li>\n <li>Minibar wird t\u00e4glich mit Erfrischungsgetr\u00e4nken, Bier und Mineralwasser aufgef\u00fcllt.<\/li>\n <li>Strandaktivit\u00e4ten wie Kajakfahren, Bambusbootfahren, H\u00f6hlenforschung, Tintenfischangeln.<\/li>\n<\/ul>\n<h6 class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">GRAND PREMIUM-ZIMMER DES SOFITEL LEGEND METROPOLE HOTEL<\/h6>\n<ul style=\"text-align: justify;\">\n <li class=\"su-column-inner su-clearfix\">48 m2 im Opernfl\u00fcgel mit Zugang zum Club Metropole f\u00fcr 2 Tage<\/li>\n <li class=\"su-column-inner su-clearfix\">Sofitel MyBed mit Kingsize-Bett, Zustellbett auf Anfrage<\/li>\n <li class=\"su-column-inner su-clearfix\">Wundersch\u00f6nes Badezimmer mit Badewanne im franz\u00f6sischen Stil und separater Dusche<\/li>\n <li class=\"su-column-inner su-clearfix\">Flachbildfernseher mit DVD-Player, Espressomaschine.<\/li>\n <li class=\"su-column-inner su-clearfix\">Zu den Vorteilen des Club Metropole geh\u00f6ren Fr\u00fchst\u00fcck, WLAN auf dem Zimmer<\/li>\n <li class=\"su-column-inner su-clearfix\">Abendcocktails, Versammlungsr\u00e4ume, Ortsgespr\u00e4che, Tee &amp; Kaffee<\/li>\n <li class=\"su-column-inner su-clearfix\">Majordomo-Service rund um die Uhr<\/li>\n <li>Pflegeprodukte von Hermes<\/li>\n<\/ul>\n<h6 class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\"><strong>BEDINGUNGEN &amp; BEDINGUNGEN<\/strong><\/h6>\n<ul style=\"text-align: justify;\">\n <li class=\"su-column-inner su-clearfix\">G\u00fcltigkeit vom 02.05.2018 bis 30.09.2018<\/li>\n <li class=\"su-column-inner su-clearfix\">Die Passagierinformation muss alle Passagierdaten mindestens 72 Stunden vor dem Check-in \u00fcbermitteln<\/li>\n <li class=\"su-column-inner su-clearfix\">Stornierungsbedingungen: Mehr als 14 Tage vor Reiseantritt, innerhalb von 14 Tagen kostenlos; 3 Tage vor Ankunft: 50 % Geb\u00fchr Weniger als 72 Stunden vor dem Check-in 100 % der Gesamtgeb\u00fchr &amp; nicht erstattungsf\u00e4hig<\/li>\n <li class=\"su-column-inner su-clearfix\">Vollst\u00e4ndige Zahlung bei Buchung.<\/li>\n <li class=\"su-column-inner su-clearfix\">Nicht stornierbar und nicht erstattungsf\u00e4hig nach erfolgter Zahlung<\/li>\n<\/ul>\n<h5 class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\"><strong>AUSSCHLUSS<\/strong><\/h5>\n<ul>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Flugpreise zum und vom Flughafen Noi Bai, Hanoi oder Cat Bi, Haiphong<\/li>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Mahlzeit (anders als im Programm erw\u00e4hnt)<\/li>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Mineralwasser \u00fcber das Angebot hinaus, Trinkgelder, fr\u00fcher Check-in oder sp\u00e4ter Check-out<\/li>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Pers\u00f6nliche Ausgaben<\/li>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Visavereinbarungen<\/li>\n <li class=\"su-column-inner su-clearfix\" style=\"text-align: justify;\">Alle anderen oben nicht erw\u00e4hnten Dienste<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1873\" aria-expanded=\"false\">REISEKARTE<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1873\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1873\" tabindex=\"0\" hidden=\"hidden\"><p><img loading=\"lazy\" class=\"alignnone size-large wp-image-20748\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/tripmap-1024x697.jpg\" alt=\"\" width=\"1024\" height=\"697\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1874\" aria-expanded=\"false\">TOURPREIS<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1874\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1874\" tabindex=\"0\" hidden=\"hidden\"><p><strong>Preis auf Anfrage. Bitte senden Sie eine Anfrage an uns! Vielen Dank.<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c76c58 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4c76c58\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e5b2d0 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"7e5b2d0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b74671a sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"b74671a\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_icon\" ><h4 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_icon sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">SENDEN SIE IHRE ANFRAGE<\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20cda79 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center sc_fly_static elementor-widget elementor-widget-divider\" data-id=\"20cda79\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);-ms-flex-negative:0;flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:-webkit-box;display:-ms-flexbox;display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-container>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow,0)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-gg\"><use xlink:href=\"#fab-gg\" \/><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556e0b2 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"556e0b2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d162a74 sc_fly_static elementor-widget elementor-widget-trx_sc_contact_form_7\" data-id=\"d162a74\" data-element_type=\"widget\" data-widget_type=\"trx_sc_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f27090-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/27400#wpcf7-f27090-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"27090\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f27090-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/div>\n<div class=\"form-style-6\">\n\t<div class=\"columns_wrap\">\n\t<span class=\"wpcf7-form-control-wrap referlink\" data-name=\"referlink\"><input type=\"hidden\" name=\"referlink\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"><\/span>\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-name\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vollst\u00e4ndiger Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-email\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"style-line icon-phone\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefonnummer\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"column-1_1\">\n\t\t<p>Anfrage:\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-home\"><span class=\"wpcf7-form-control-wrap package\" data-name=\"package\"><input type=\"text\" name=\"package\" class=\"wpcf7-form-control wpcf7-text wpcf7dtx wpcf7dtx-text\" aria-invalid=\"false\" readonly=\"readonly\" value=\"Erleben Sie Hanoi &amp; Halong Bucht in 5 Tagen\"><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap\">\n\t\t<div class=\"column-1_2\">\n\t\t\t<p>Eincheckdatum\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-1_2\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"check-in\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"check-in\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"columns_wrap margin-bottom\">\n\t\t<div class=\"column-1_1\">\n\t\t\t<p><span class=\"style-line icon-textarea\"><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Bitte schreiben Sie Ihre Anfrage!\" name=\"message\"><\/textarea><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<p><div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-3226784069\" class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAAB5BkqQC2N9TqUgz\" data-theme=\"light\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-refresh-expired=\"auto\" data-refresh-timeout=\"auto\" data-action=\"contact-form-7\" data-callback=\"turnstileCF7Callback\" data-appearance=\"always\"><\/div> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-3226784069\"> <style>#cf-turnstile-cf7-3226784069 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-3226784069')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-3226784069');},1000)}})})});<\/script> <\/div><br \/>\n<input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"Senden\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33e8639 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"33e8639\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff4bc8 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3ff4bc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d08846 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3d08846\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d0e003 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1d0e003\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a819c1 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1a819c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-112e782 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"112e782\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-271e1cc sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"271e1cc\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">SIE K\u00d6NNTEN INTERESSIEREN<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">ALLE UNSERE ERFAHRUNGEN<\/span><\/h2><div class=\"sc_item_descr sc_title_descr sc_align_center\"><p>G\u00f6nnen Sie sich ein einmaliges Erlebnis in Vietnam, indem Sie an Bord unserer Emperor Cruises gehen und in der Halong-Bucht kreuzen. Wagen Sie sich abseits der ausgetretenen Pfade, gehen Sie Kajak fahren und besuchen Sie schwimmende Fischfarmen und D\u00f6rfer, um das t\u00e4gliche Leben der Einheimischen zu erleben.<\/p>\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352cead sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"352cead\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-646e8ed sc_fly_static elementor-widget elementor-widget-trx_sc_services\" data-id=\"646e8ed\" data-element_type=\"widget\" data-widget_type=\"trx_sc_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sc_services sc_services_classic sc_services_featured_top\"><div class=\"sc_services_columns_wrap sc_item_columns sc_item_posts_container sc_item_columns_3 trx_addons_columns_wrap columns_padding_bottom\"><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27359\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27359 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2025\/10\/z7070168481550_1164f498cac7f48786aa0367042755ff-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/kaisererlebnis-2-tage\/\">Kaisererlebnis 2 Tage<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/kaisererlebnis-2-tage\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/kaisererlebnis-2-tage\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27374\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27374 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-16-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/kaiserversteck-3-tage\/\">Kaiserversteck 3 Tage<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/kaiserversteck-3-tage\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/kaiserversteck-3-tage\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27386\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27386 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2020\/04\/Welcome-lifestyle-7-840x559.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-4-tagen\/\">Erleben Sie Hanoi &#038; Halong Bucht in 4 Tagen<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-4-tagen\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-4-tagen\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27400\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27400 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Beach-Lifestyle-20-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-5-tagen\/\">Erleben Sie Hanoi &#038; Halong Bucht in 5 Tagen<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-5-tagen\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/erleben-sie-hanoi-halong-bucht-in-5-tagen\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27418\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27418 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Welcome-lifestyle-6-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/charter-kreuzfahrten\/\">Charter Kreuzfahrten<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/charter-kreuzfahrten\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/charter-kreuzfahrten\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 \"><div data-post-id=\"27427\" class=\"sc_services_item sc_item_container post_container with_more without_content with_image sc_services_item_featured_none post-27427 page type-page status-publish has-post-thumbnail hentry\">\n\t\t<div class=\"sc_services_item_content \" style=\"background-image: url(https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/06\/Welcome-lifestyle-2-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_bottom\"><div class=\"sc_services_item_info_wrap\">\n                    <div class=\"sc_services_item_title_wrap\">\n                        <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/emperorcruises.com\/de\/limousinen-service\/\">Limousinen Service<\/a><\/h6>\n                        <div class=\"sc_services_item_subtitle\"><\/div><\/div><div class=\"sc_services_item_button sc_item_button\">\n                        <a href=\"https:\/\/emperorcruises.com\/de\/limousinen-service\/\" class=\"sc_services_item_more_link\">\n                            <span class=\"link_text\">Read More<\/span><span class=\"link_icon\"><\/span>\n                        <\/a>\n                        <\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/emperorcruises.com\/de\/limousinen-service\/\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0055001 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0055001\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90a3875 scheme_default elementor-section-stretched sc_layouts_hide_on_mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"90a3875\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20f1a6b sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"20f1a6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c769f0e sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c769f0e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e79087 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"5e79087\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">WAS UNSERE KUNDEN \u00dcBER UNS SAGEN<\/span><h2 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">REFERENZEN<\/span><\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b87d26 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0b87d26\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c6c51b sc_fly_static elementor-widget elementor-widget-trx_sc_testimonials\" data-id=\"2c6c51b\" data-element_type=\"widget\" data-widget_type=\"trx_sc_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \t\tclass=\"sc_testimonials sc_testimonials_hover\"><div class=\"sc_testimonials_columns_wrap sc_item_columns trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\"><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27547\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Perfekt von Anfang bis Ende, entscheiden Sie sich f\u00fcr die Royal Suite<\/strong>\u00a0\u2013 Wundersch\u00f6nes Schiff mit wunderbarem Personal. Nur 8 Zimmer machen die Reise zu etwas ganz Besonderem. Wir haben die Royal Suite &#8222;King Room&#8220; gebucht. Dieses sehr \u00fcbergro\u00dfe Zimmer mit Platz im Freien vor dem Schiff. Das Bett schl\u00e4ft fantastisch, der Whirlpool ist ein einzigartiges Erlebnis. Unser Butler-Sohn war der beste. Sehr kompetent und so freundlich! Er hat alles getan, um es zu etwas Besonderem zu machen. Wir haben eines Abends unser Jubil\u00e4um gefeiert. Der Einsatz des Teams war brillant. Ein Strau\u00df frischer Rosen, ein gro\u00dfer Kuchen und eine sch\u00f6ne Rede von Manager Quang. Ann, Abby und Barkeeper Jack waren gro\u00dfartig und aufmerksam, ebenso wie unser Reiseleiter Wind. Wenn Sie ein Jubil\u00e4um feiern oder einen Antrag machen m\u00f6chten, tun Sie dies hier. Uns gefiel auch die Reiseroute der 2 N\u00e4chte, 3 Tage, da Sie auf einem kleineren Boot einen einzigartigen Blick auf die Bucht haben.<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"Jorrit88\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/jorrit88.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Jorrit88<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">New York City, New York<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27551\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Exzellenz und Gelassenheit<\/strong> \u2013 Mein Mann und ich genossen eine zweit\u00e4gige Kreuzfahrt mit Emperor Cruises in der Halong-Bucht. Das Personal war absolut entz\u00fcckend und aufmerksam auf alle Ihre Bed\u00fcrfnisse. Das Essen war reichlich und sehr gut. Bei unseren Ausfl\u00fcgen an Land war unser Reiseleiter sachkundig, hilfsbereit und auf alles vorbereitet \u2013 Mittagessen, Wetter und alles, was f\u00fcr Sicherheit und Komfort erforderlich war. Wir haben die ganze Erfahrung geliebt und k\u00f6nnen es w\u00e4rmstens empfehlen, wenn Sie die Gegend besuchen. Ein Tipp &#8211; die 2-N\u00e4chte-Option bot die beste Gelegenheit, die Gegend wirklich zu genie\u00dfen.<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"franee0409\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/avatar.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">franee0409<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">New York City, New York<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"trx_addons_column-1_3\"><div data-post-id=\"27555\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\"><p style=\"text-align: justify;\"><small><strong>Faszinierende Landschaften in einem pr\u00e4chtigen Kreuzfahrtschiff in der Bucht von Halong Bay!<\/strong> &#8211; Eine Kreuzfahrt mit Emperor Cruise in Halong macht unseren Urlaub noch spezieller und unvergesslicher dieses wunderbare Land! Wir waren schon auf verschiedenen internationalen Kreuzfahrtschiffen, aber dieses ist ziemlich einzigartig und authentisch, da das Konzept dieses Bootes die Geschichte und Kultur Vietnams mit sehr detaillierten Gem\u00e4lden in jeder Ecke an Bord zeigte. Abgesehen von seinem atemberaubenden Boot ist das Team auf diesem Boot ausgezeichnet, besonders Chris, der unter allen flie\u00dfend Englisch spricht. Emperor Boat bot auch eine Vielzahl von Aktivit\u00e4ten innerhalb und au\u00dferhalb von Exkursionen an, aber nat\u00fcrlich k\u00f6nnen Sie w\u00e4hlen, ob Sie an Bord gehen oder auf dem Hauptschiff bleiben m\u00f6chten, um sich zu entspannen. Das Essen ist perfekt und die Menge ist zu viel! Dieses Schiff ist wirklich ein 5 * f\u00fcr uns! F\u00fcgen Sie einfach mehr englischsprachiges Personal f\u00fcr eine bessere Kommunikation an Bord hinzu!<\/small><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t\t<div class=\"sc_testimonials_item_author_avatar\"><img width=\"120\" height=\"120\" src=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4-120x120.jpg\" class=\"attachment-qwery-thumb-tiny size-qwery-thumb-tiny wp-post-image\" alt=\"Rasmus Engkeb\u00f8lle\" loading=\"lazy\" srcset=\"https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4-120x120.jpg 120w, https:\/\/emperorcruises.com\/wp-content\/uploads\/2022\/07\/default-avatar-2020-4.jpg 150w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/div>\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Rasmus Engkeb\u00f8lle<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Roskilde, Denmark<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><!-- \/.sc_testimonials -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfa3173 sc_layouts_hide_on_tablet sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"bfa3173\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c0f3e6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"2c0f3e6\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8b444c sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f8b444c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e0ba12 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2e0ba12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EMPEROR CRUISES LEGACY HALONG Erleben Sie Hanoi &#038; Halong Bucht in 5 Tagen Vietnams allererste All-Inclusive-\u00dcbernachtkreuzfahrten in der Halong-Bucht Erleben Sie Hanoi &#038; Halong Bucht in 5 Tagen Erlebe jeden&nbsp;Augenblick!&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22680,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/pages\/27400"}],"collection":[{"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/comments?post=27400"}],"version-history":[{"count":13,"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/pages\/27400\/revisions"}],"predecessor-version":[{"id":40936,"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/pages\/27400\/revisions\/40936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/media\/22680"}],"wp:attachment":[{"href":"https:\/\/emperorcruises.com\/de\/wp-json\/wp\/v2\/media?parent=27400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}